{"id":3631,"date":"2026-05-12T17:57:31","date_gmt":"2026-05-12T23:57:31","guid":{"rendered":"https:\/\/somos-hermanos.mx\/?p=3631"},"modified":"2026-05-12T18:13:11","modified_gmt":"2026-05-13T00:13:11","slug":"para-permanecer-alegres-necesitamos-la-paciencia","status":"publish","type":"post","link":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/para-permanecer-alegres-necesitamos-la-paciencia\/","title":{"rendered":"Para permanecer alegres necesitamos la paciencia"},"content":{"rendered":"<p><strong>Redacci\u00f3n:<\/strong> Gabriel Mart\u00ednez Navarrete<\/p>\n<p>&nbsp;<\/p>\n<h4>Descubre c\u00f3mo la virtud de la paciencia y el optimismo vencen a la tristeza. Consejos y reflexiones filos\u00f3ficas para vivir con alegr\u00eda.<\/h4>\n<p>Est\u00e1n tristes algunos viejos que se preocupan demasiado por su porvenir, cuando en realidad lo tienen ya agotado&#8230; Este exceso de preocupaci\u00f3n proviene muchas veces de falta de sinceridad.<\/p>\n<p>Nos organizamos tanto que damos m\u00e1s valor a un escrito que a una persona. Para que la palabra de dos personas se cumpla hace falta de un notario\u2026 No me refiero al papel tan \u00fatil del notario en la sociedad: su importante funci\u00f3n salta a la vista.<\/p>\n<p>La alegr\u00eda se consigue tratando de vivir la sinceridad y el olvido de s\u00ed. Puntualizar para no llegar -pase lo que pase- a conclusiones pesimistas.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Confiemos en los dem\u00e1s.<\/strong><\/p>\n<p>Pongamos optimismo y buen humor en nuestras vidas, lo que ser\u00e1 m\u00e1s f\u00e1cil si metemos a Dios en lo que pensamos y hacemos. La pasaremos mejor: pues en igualdad de condiciones sale siempre ganando quien toma las cosas con optimismo y buen humor.<\/p>\n<p>Existe una gran diferencia entre el buen humor y el car\u00e1cter avinagrado.<\/p>\n<p>Ver el lado positivo de las cosas y, si es el caso, actuar en consecuencia para remediar la situaci\u00f3n. Ir siempre hacia adelante \u2013no importan las dificultades- gozando la vida.<\/p>\n<p>Siendo objetivos y veraces. Lo que hay que corregir, se corrige y se sigue hacia adelante. Pensar, antes de hacer, y el camino se har\u00e1 m\u00e1s f\u00e1cil. Saber a d\u00f3nde nos encontraremos para tomar la decisi\u00f3n siguiente y tener el objetivo claro hacia d\u00f3nde nos dirigimos.<\/p>\n<p>El optimista siempre tiene un proyecto. El pesimista tiene siempre una excusa. El secreto del buen humor, est\u00e1 m\u00e1s en olvidarse de s\u00ed y en contagiarlo, m\u00e1s que en esperarlo.<\/p>\n<p>Tanto el optimismo y el buen humor son constantes y van siempre de la mano.<\/p>\n<p>La tristeza es la pasi\u00f3n m\u00e1s terrible que impide la acci\u00f3n de la raz\u00f3n. Se necesita una virtud que anonade a la tristeza y nos haga alegres, la cual es la paciencia.<\/p>\n<p>Con la paciencia \u201csoportamos los males con igualdad de \u00e1nimo, sin que la cobard\u00eda nos haga abandonar el bien que ha de conducirnos a los cielos\u201d (san Agust\u00edn).<\/p>\n<p>La paciencia hace soportar la adversidad: Reprime primero la tristeza, evita el odio, deja campo libre a la caridad e impide las reclamaciones injustas.<\/p>\n<p>La caridad es paciente. \u201cEl ardor del deseo produce la tolerancia de las penas y de los dolores; nadie consiente de buena gana en lo que lo tortura, si no es a causa de lo que le regocija\u201d (san Agust\u00edn).<\/p>\n<p>La paciencia es la ra\u00edz de las otras virtudes porque aparta los obst\u00e1culos para su ejercicio, por ejemplo: la virtud de la longanimidad: atiende a un bien m\u00e1s o menos lejano, y no se desanima por la prolongada espera en conseguirlo.<\/p>\n<p>La virtud de la constancia: no contenta con esperar pacientemente el bien que resultar\u00e1 de la pena, se dedica con obstinado trabajo en realizar ese fin.<\/p>\n<p>Para \u201chacer el bien\u201d hay que acometer empresas arduas y para \u201cevitar el mal\u201d hay que sufrir situaciones muy diversas. La paciencia se considera, por tanto, una parte de la fortaleza. Especialmente si se trata de sufrir las contradicciones como el dolor, y la m\u00e1s fuerte para el hombre, como es la muerte.<\/p>\n<p>La paciencia en cu\u00e1nto h\u00e1bito nos conduce a una firme adhesi\u00f3n al bien; s\u00f3lo la adhesi\u00f3n al bien que peligra, hace posible rechazar el mal que se le opone.<\/p>\n<p>Santo Tom\u00e1s define la paciencia como la virtud, por la que los males presentes se soportan de tal modo, que de ellos no se deriva nunca una tristeza sobrenatural. La paciencia permite estar alegremente unidos a Dios.<\/p>\n<p>La paciencia en cu\u00e1nto h\u00e1bito nos conduce a una firme adhesi\u00f3n al bien; s\u00f3lo la adhesi\u00f3n al bien que peligra, hace posible rechazar el mal que se le opone. Santo Tom\u00e1s define la paciencia como la virtud, por la que los males presentes se soportan de tal modo, que de ellos no se deriva nunca una tristeza sobrenatural.<\/p>\n<p>Con la perseverancia est\u00e1 relacionada la paciencia, porque ambas son parte de la fortaleza en cuanto es propio de esta virtud cardinal resistir el mal. La paciencia fortalece al alma para que supere la tristeza proveniente de los males que hay que soportar.<\/p>\n<p>Solo la caridad \u2013el amor a Dios m\u00e1s que todo- inspira el sacrificarle todos los bienes creados, por lo tanto: soportar con alegr\u00eda todas las penas que resultan de la privaci\u00f3n.<\/p>\n<p>\u201cUn remedio contra esas inquietudes tuyas: tener paciencia, rectitud de intenci\u00f3n, y mirar las cosas con perspectiva sobrenatural\u201d (san Josemar\u00eda Escriv\u00e1. Surco, n.853).<\/p>\n<p>La paciencia \u201csoporta voluntariamente y todo el tiempo que sea necesario, cosas dif\u00edciles penosas, por un objetivo penoso y \u00fatil.\u201d (Cicer\u00f3n).<\/p>\n<p>Es importante que nos eduquemos en la paciencia. No nacemos pacientes: Como toda virtud esta se adquiere con repetici\u00f3n de actos.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/encrypted-tbn0.gstatic.com\/images?q=tbn:ANd9GcQLnvFMMuhSZMrIPWMPcSPq3KaSYScaVf04IQ&amp;s\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Redacci\u00f3n: Gabriel Mart\u00ednez Navarrete &nbsp; Descubre c\u00f3mo la virtud de la paciencia y el optimismo vencen a la tristeza. Consejos y reflexiones filos\u00f3ficas para vivir con alegr\u00eda. Est\u00e1n tristes algunos viejos que se preocupan demasiado por su porvenir, cuando en realidad lo tienen ya agotado&#8230; Este exceso de preocupaci\u00f3n proviene muchas veces de falta de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":3634,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,24],"tags":[4592,4488,4589,4591,4409,4590],"class_list":["post-3631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-columnas","category-gabriel-martinez-navarrete","tag-fortaleza","tag-opinion","tag-paciencia","tag-santo","tag-somos-hermanos","tag-virtud"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Para permanecer alegres necesitamos la paciencia - Historias que inspiran...<\/title>\n<meta name=\"description\" content=\"Descubre c\u00f3mo la virtud de la paciencia y el optimismo vencen a la tristeza. Consejos y reflexiones filos\u00f3ficas para vivir con alegr\u00eda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/para-permanecer-alegres-necesitamos-la-paciencia\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Para permanecer alegres necesitamos la paciencia - Historias que inspiran...\" \/>\n<meta property=\"og:description\" content=\"Descubre c\u00f3mo la virtud de la paciencia y el optimismo vencen a la tristeza. Consejos y reflexiones filos\u00f3ficas para vivir con alegr\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/para-permanecer-alegres-necesitamos-la-paciencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Historias que inspiran...\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SomosHermanosIAP\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T23:57:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T00:13:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/somos-hermanos.mx\/wp-content\/uploads\/2026\/05\/paciencia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriel Mart\u00ednez Navarrete\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Somos__Hermanos\" \/>\n<meta name=\"twitter:site\" content=\"@Somos__Hermanos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Mart\u00ednez Navarrete\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/para-permanecer-alegres-necesitamos-la-paciencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/para-permanecer-alegres-necesitamos-la-paciencia\\\/\"},\"author\":{\"name\":\"Gabriel Mart\u00ednez Navarrete\",\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/#\\\/schema\\\/person\\\/44f957c5358a517057be2865328aafa1\"},\"headline\":\"Para permanecer alegres necesitamos la paciencia\",\"datePublished\":\"2026-05-12T23:57:31+00:00\",\"dateModified\":\"2026-05-13T00:13:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/para-permanecer-alegres-necesitamos-la-paciencia\\\/\"},\"wordCount\":876,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/para-permanecer-alegres-necesitamos-la-paciencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/somos-hermanos.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/paciencia.jpg\",\"keywords\":[\"fortaleza\",\"opini\u00f3n\",\"paciencia\",\"santo\",\"Somos Hermanos\",\"virtud\"],\"articleSection\":[\"Columnas\",\"Gabriel Mart\u00ednez Navarrete\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/para-permanecer-alegres-necesitamos-la-paciencia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/para-permanecer-alegres-necesitamos-la-paciencia\\\/\",\"url\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/para-permanecer-alegres-necesitamos-la-paciencia\\\/\",\"name\":\"Para permanecer alegres necesitamos la paciencia - Historias que inspiran...\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/para-permanecer-alegres-necesitamos-la-paciencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/para-permanecer-alegres-necesitamos-la-paciencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/somos-hermanos.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/paciencia.jpg\",\"datePublished\":\"2026-05-12T23:57:31+00:00\",\"dateModified\":\"2026-05-13T00:13:11+00:00\",\"description\":\"Descubre c\u00f3mo la virtud de la paciencia y el optimismo vencen a la tristeza. Consejos y reflexiones filos\u00f3ficas para vivir con alegr\u00eda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/para-permanecer-alegres-necesitamos-la-paciencia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/para-permanecer-alegres-necesitamos-la-paciencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/para-permanecer-alegres-necesitamos-la-paciencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/somos-hermanos.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/paciencia.jpg\",\"contentUrl\":\"https:\\\/\\\/somos-hermanos.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/paciencia.jpg\",\"width\":1200,\"height\":630,\"caption\":\"paciencia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/para-permanecer-alegres-necesitamos-la-paciencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/somos-hermanos.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Para permanecer alegres necesitamos la paciencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/#website\",\"url\":\"https:\\\/\\\/somos-hermanos.mx\\\/\",\"name\":\"Historias que inspiran...\",\"description\":\"Somos la voz del altruismo en M\u00e9xico\",\"publisher\":{\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/somos-hermanos.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/#organization\",\"name\":\"Somos Hermanos\",\"url\":\"https:\\\/\\\/somos-hermanos.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/somos-hermanos.mx\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/SH30-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/somos-hermanos.mx\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/SH30-1.jpeg\",\"width\":1600,\"height\":1142,\"caption\":\"Somos Hermanos\"},\"image\":{\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SomosHermanosIAP\\\/\",\"https:\\\/\\\/x.com\\\/Somos__Hermanos\",\"https:\\\/\\\/www.instagram.com\\\/somos__hermanos\\\/#\",\"https:\\\/\\\/www.tiktok.com\\\/@somoshermanosiap\",\"https:\\\/\\\/www.youtube.com\\\/@somoshermanosiap1201\\\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/#\\\/schema\\\/person\\\/44f957c5358a517057be2865328aafa1\",\"name\":\"Gabriel Mart\u00ednez Navarrete\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1566a69e29b83b6a8cea93c853aac1e42bcc49d57e43801948d25b3bd2c4404c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1566a69e29b83b6a8cea93c853aac1e42bcc49d57e43801948d25b3bd2c4404c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1566a69e29b83b6a8cea93c853aac1e42bcc49d57e43801948d25b3bd2c4404c?s=96&d=mm&r=g\",\"caption\":\"Gabriel Mart\u00ednez Navarrete\"},\"url\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/author\\\/gabriel-garcia-navarrete\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Para permanecer alegres necesitamos la paciencia - Historias que inspiran...","description":"Descubre c\u00f3mo la virtud de la paciencia y el optimismo vencen a la tristeza. Consejos y reflexiones filos\u00f3ficas para vivir con alegr\u00eda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/para-permanecer-alegres-necesitamos-la-paciencia\/","og_locale":"es_MX","og_type":"article","og_title":"Para permanecer alegres necesitamos la paciencia - Historias que inspiran...","og_description":"Descubre c\u00f3mo la virtud de la paciencia y el optimismo vencen a la tristeza. Consejos y reflexiones filos\u00f3ficas para vivir con alegr\u00eda.","og_url":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/para-permanecer-alegres-necesitamos-la-paciencia\/","og_site_name":"Historias que inspiran...","article_publisher":"https:\/\/www.facebook.com\/SomosHermanosIAP\/","article_published_time":"2026-05-12T23:57:31+00:00","article_modified_time":"2026-05-13T00:13:11+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/somos-hermanos.mx\/wp-content\/uploads\/2026\/05\/paciencia.jpg","type":"image\/jpeg"}],"author":"Gabriel Mart\u00ednez Navarrete","twitter_card":"summary_large_image","twitter_creator":"@Somos__Hermanos","twitter_site":"@Somos__Hermanos","twitter_misc":{"Escrito por":"Gabriel Mart\u00ednez Navarrete","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/para-permanecer-alegres-necesitamos-la-paciencia\/#article","isPartOf":{"@id":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/para-permanecer-alegres-necesitamos-la-paciencia\/"},"author":{"name":"Gabriel Mart\u00ednez Navarrete","@id":"https:\/\/somos-hermanos.mx\/#\/schema\/person\/44f957c5358a517057be2865328aafa1"},"headline":"Para permanecer alegres necesitamos la paciencia","datePublished":"2026-05-12T23:57:31+00:00","dateModified":"2026-05-13T00:13:11+00:00","mainEntityOfPage":{"@id":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/para-permanecer-alegres-necesitamos-la-paciencia\/"},"wordCount":876,"commentCount":0,"publisher":{"@id":"https:\/\/somos-hermanos.mx\/#organization"},"image":{"@id":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/para-permanecer-alegres-necesitamos-la-paciencia\/#primaryimage"},"thumbnailUrl":"https:\/\/somos-hermanos.mx\/wp-content\/uploads\/2026\/05\/paciencia.jpg","keywords":["fortaleza","opini\u00f3n","paciencia","santo","Somos Hermanos","virtud"],"articleSection":["Columnas","Gabriel Mart\u00ednez Navarrete"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/para-permanecer-alegres-necesitamos-la-paciencia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/para-permanecer-alegres-necesitamos-la-paciencia\/","url":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/para-permanecer-alegres-necesitamos-la-paciencia\/","name":"Para permanecer alegres necesitamos la paciencia - Historias que inspiran...","isPartOf":{"@id":"https:\/\/somos-hermanos.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/para-permanecer-alegres-necesitamos-la-paciencia\/#primaryimage"},"image":{"@id":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/para-permanecer-alegres-necesitamos-la-paciencia\/#primaryimage"},"thumbnailUrl":"https:\/\/somos-hermanos.mx\/wp-content\/uploads\/2026\/05\/paciencia.jpg","datePublished":"2026-05-12T23:57:31+00:00","dateModified":"2026-05-13T00:13:11+00:00","description":"Descubre c\u00f3mo la virtud de la paciencia y el optimismo vencen a la tristeza. Consejos y reflexiones filos\u00f3ficas para vivir con alegr\u00eda.","breadcrumb":{"@id":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/para-permanecer-alegres-necesitamos-la-paciencia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/para-permanecer-alegres-necesitamos-la-paciencia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/para-permanecer-alegres-necesitamos-la-paciencia\/#primaryimage","url":"https:\/\/somos-hermanos.mx\/wp-content\/uploads\/2026\/05\/paciencia.jpg","contentUrl":"https:\/\/somos-hermanos.mx\/wp-content\/uploads\/2026\/05\/paciencia.jpg","width":1200,"height":630,"caption":"paciencia"},{"@type":"BreadcrumbList","@id":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/para-permanecer-alegres-necesitamos-la-paciencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/somos-hermanos.mx\/"},{"@type":"ListItem","position":2,"name":"Para permanecer alegres necesitamos la paciencia"}]},{"@type":"WebSite","@id":"https:\/\/somos-hermanos.mx\/#website","url":"https:\/\/somos-hermanos.mx\/","name":"Historias que inspiran...","description":"Somos la voz del altruismo en M\u00e9xico","publisher":{"@id":"https:\/\/somos-hermanos.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/somos-hermanos.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/somos-hermanos.mx\/#organization","name":"Somos Hermanos","url":"https:\/\/somos-hermanos.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/somos-hermanos.mx\/#\/schema\/logo\/image\/","url":"https:\/\/somos-hermanos.mx\/wp-content\/uploads\/2025\/08\/SH30-1.jpeg","contentUrl":"https:\/\/somos-hermanos.mx\/wp-content\/uploads\/2025\/08\/SH30-1.jpeg","width":1600,"height":1142,"caption":"Somos Hermanos"},"image":{"@id":"https:\/\/somos-hermanos.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SomosHermanosIAP\/","https:\/\/x.com\/Somos__Hermanos","https:\/\/www.instagram.com\/somos__hermanos\/#","https:\/\/www.tiktok.com\/@somoshermanosiap","https:\/\/www.youtube.com\/@somoshermanosiap1201\/videos"]},{"@type":"Person","@id":"https:\/\/somos-hermanos.mx\/#\/schema\/person\/44f957c5358a517057be2865328aafa1","name":"Gabriel Mart\u00ednez Navarrete","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1566a69e29b83b6a8cea93c853aac1e42bcc49d57e43801948d25b3bd2c4404c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1566a69e29b83b6a8cea93c853aac1e42bcc49d57e43801948d25b3bd2c4404c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1566a69e29b83b6a8cea93c853aac1e42bcc49d57e43801948d25b3bd2c4404c?s=96&d=mm&r=g","caption":"Gabriel Mart\u00ednez Navarrete"},"url":"https:\/\/somos-hermanos.mx\/index.php\/author\/gabriel-garcia-navarrete\/"}]}},"_links":{"self":[{"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/posts\/3631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3631"}],"version-history":[{"count":2,"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/posts\/3631\/revisions"}],"predecessor-version":[{"id":3635,"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/posts\/3631\/revisions\/3635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/media\/3634"}],"wp:attachment":[{"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}