{"id":3628,"date":"2026-05-12T17:46:31","date_gmt":"2026-05-12T23:46:31","guid":{"rendered":"https:\/\/somos-hermanos.mx\/?p=3628"},"modified":"2026-05-12T17:46:31","modified_gmt":"2026-05-12T23:46:31","slug":"infancia-y-derecho-a-la-atencion-medica","status":"publish","type":"post","link":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/infancia-y-derecho-a-la-atencion-medica\/","title":{"rendered":"Infancia y derecho a la atenci\u00f3n m\u00e9dica"},"content":{"rendered":"<h4><span class=\"TextRun SCXW107702693 BCX0\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW107702693 BCX0\">Infancia y derecho a la atenci\u00f3n m\u00e9dica: descubre c\u00f3mo millones de ni\u00f1as y ni\u00f1os en M\u00e9xico enfrentan barreras para acceder a servicios de salud, y c\u00f3mo fundaciones como Lilo trabajan para garantizar diagn\u00f3sticos tempranos y tratamientos que salvan vidas.<\/span><\/span><span class=\"EOP SCXW107702693 BCX0\" data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/h4>\n<p><span data-contrast=\"auto\">La atenci\u00f3n m\u00e9dica es un derecho fundamental e internacional, el cual garantiza que todas las personas puedan acceder a una asistencia de calidad, que les asegure el m\u00e1s alto nivel de bienestar f\u00edsico y mental. Este derecho busca dignificar a las personas y garantizar una buena calidad de vida; asimismo, fue reconocido por la Constituci\u00f3n de la OMS en 1846 y la Declaraci\u00f3n Universal de Derechos Humanos de 1948.\u00a0<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559731&quot;:720}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">El Estado es el principal mediador para su realizaci\u00f3n. Los gobiernos deben facilitar los medios y espacios para ofrecer un servicio m\u00e9dico.\u00a0<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Ante los \u00faltimos resultados, est\u00e1 claro que hay una misi\u00f3n con las infancias, pues alrededor de 15 millones de\u00a0ni\u00f1os y ni\u00f1as\u00a0no pueden acceder a esta atenci\u00f3n. Estas cifras representan el 45% de la poblaci\u00f3n infantil en el pa\u00eds. Las instituciones de salud p\u00fablica tienen la obligaci\u00f3n de invertir y fomentar espacios donde las infancias puedan atender sus necesidades y gozar de un crecimiento digno y seguro.\u00a0<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Los estudios han demostrado un incremento en la poblaci\u00f3n infantil sin acceso a la salud; entre 2016 se hab\u00eda registrado cinco millones, pero en el 2022 se dio a conocer que se triplic\u00f3 y alcanz\u00f3 los 15 millones. Los estados que m\u00e1s necesitan de atenci\u00f3n m\u00e9dica son Guerrero, Michoac\u00e1n, Hidalgo, Oaxaca y Chiapas, en estos territorios alrededor del 58% de este sector no cuenta con la atenci\u00f3n ya mencionada.\u00a0<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559731&quot;:720}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">La lucha por este derecho debe ser una prioridad y con una estrategia a largo plazo. Los infantes sin acceso a la atenci\u00f3n m\u00e9dica son cada vez m\u00e1s. Una forma de ofrecer ayuda es apoyando a fundaciones que, gracias a su esfuerzo e iniciativa, logran acercar los medios para que diversos ni\u00f1os tengan oportunidad de tratar o prevenir alguna afecci\u00f3n.\u00a0<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Un ejemplo de esto es Lilo Fundaci\u00f3n, un proyecto que busca ayudar a reci\u00e9n nacidos que padecen cardiopat\u00edas cong\u00e9nitas; una de las principales causas de muerte en la infancia. Su detecci\u00f3n temprana y tratamiento ayuda a aumentar y fortalecer la vida de\u00a0ni\u00f1os y ni\u00f1as\u00a0que la padecen.\u00a0<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Su objetivo es ayudar al sistema de salud ampliando los espacios de atenci\u00f3n m\u00e9dica especializada en el pa\u00eds. Asimismo, est\u00e1n comprometidos con visibilizar la informaci\u00f3n relacionada con este padecimiento y lograr que se puedan detectar y tratar a tiempo.\u00a0<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Al compartir en redes sociales o realizar una donaci\u00f3n a este tipo de fundaciones, se ayuda a que la brecha sea cada vez menor y m\u00e1s infancias disfruten de ese derecho esencial que es la atenci\u00f3n m\u00e9dica.\u00a0<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Infancia y derecho a la atenci\u00f3n m\u00e9dica: descubre c\u00f3mo millones de ni\u00f1as y ni\u00f1os en M\u00e9xico enfrentan barreras para acceder a servicios de salud, y c\u00f3mo fundaciones como Lilo trabajan para garantizar diagn\u00f3sticos tempranos y tratamientos que salvan vidas.\u00a0 La atenci\u00f3n m\u00e9dica es un derecho fundamental e internacional, el cual garantiza que todas las personas [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":3629,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[101,4099,3182,4510,4588,2886],"class_list":["post-3628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-atencion-medica","tag-comunidad","tag-derecho","tag-infancia","tag-infancia-y-derecho","tag-salud"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Infancia y derecho a la atenci\u00f3n m\u00e9dica - Historias que inspiran...<\/title>\n<meta name=\"description\" content=\"Infancia y derecho a la atenci\u00f3n m\u00e9dica: descubre c\u00f3mo millones de ni\u00f1as y ni\u00f1os en M\u00e9xico enfrentan barreras para acceder\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/infancia-y-derecho-a-la-atencion-medica\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Infancia y derecho a la atenci\u00f3n m\u00e9dica - Historias que inspiran...\" \/>\n<meta property=\"og:description\" content=\"Infancia y derecho a la atenci\u00f3n m\u00e9dica: descubre c\u00f3mo millones de ni\u00f1as y ni\u00f1os en M\u00e9xico enfrentan barreras para acceder\" \/>\n<meta property=\"og:url\" content=\"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/infancia-y-derecho-a-la-atencion-medica\/\" \/>\n<meta property=\"og:site_name\" content=\"Historias que inspiran...\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SomosHermanosIAP\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T23:46:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/somos-hermanos.mx\/wp-content\/uploads\/2026\/05\/atencion-medica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jes\u00fas Pe\u00f1a Aguirre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Somos__Hermanos\" \/>\n<meta name=\"twitter:site\" content=\"@Somos__Hermanos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jes\u00fas Pe\u00f1a Aguirre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/infancia-y-derecho-a-la-atencion-medica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/infancia-y-derecho-a-la-atencion-medica\\\/\"},\"author\":{\"name\":\"Jes\u00fas Pe\u00f1a Aguirre\",\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/#\\\/schema\\\/person\\\/8acd26a8688e659352b79b33c534872c\"},\"headline\":\"Infancia y derecho a la atenci\u00f3n m\u00e9dica\",\"datePublished\":\"2026-05-12T23:46:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/infancia-y-derecho-a-la-atencion-medica\\\/\"},\"wordCount\":505,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/infancia-y-derecho-a-la-atencion-medica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/somos-hermanos.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/atencion-medica.jpg\",\"keywords\":[\"atenci\u00f3n m\u00e9dica\",\"comunidad\",\"Derecho\",\"infancia\",\"infancia y derecho\",\"salud\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/infancia-y-derecho-a-la-atencion-medica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/infancia-y-derecho-a-la-atencion-medica\\\/\",\"url\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/infancia-y-derecho-a-la-atencion-medica\\\/\",\"name\":\"Infancia y derecho a la atenci\u00f3n m\u00e9dica - Historias que inspiran...\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/infancia-y-derecho-a-la-atencion-medica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/infancia-y-derecho-a-la-atencion-medica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/somos-hermanos.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/atencion-medica.jpg\",\"datePublished\":\"2026-05-12T23:46:31+00:00\",\"description\":\"Infancia y derecho a la atenci\u00f3n m\u00e9dica: descubre c\u00f3mo millones de ni\u00f1as y ni\u00f1os en M\u00e9xico enfrentan barreras para acceder\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/infancia-y-derecho-a-la-atencion-medica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/infancia-y-derecho-a-la-atencion-medica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/infancia-y-derecho-a-la-atencion-medica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/somos-hermanos.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/atencion-medica.jpg\",\"contentUrl\":\"https:\\\/\\\/somos-hermanos.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/atencion-medica.jpg\",\"width\":1200,\"height\":630,\"caption\":\"atenci\u00f3n m\u00e9dica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/2026\\\/05\\\/12\\\/infancia-y-derecho-a-la-atencion-medica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/somos-hermanos.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Infancia y derecho a la atenci\u00f3n m\u00e9dica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/#website\",\"url\":\"https:\\\/\\\/somos-hermanos.mx\\\/\",\"name\":\"Historias que inspiran...\",\"description\":\"Somos la voz del altruismo en M\u00e9xico\",\"publisher\":{\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/somos-hermanos.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/#organization\",\"name\":\"Somos Hermanos\",\"url\":\"https:\\\/\\\/somos-hermanos.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/somos-hermanos.mx\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/SH30-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/somos-hermanos.mx\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/SH30-1.jpeg\",\"width\":1600,\"height\":1142,\"caption\":\"Somos Hermanos\"},\"image\":{\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SomosHermanosIAP\\\/\",\"https:\\\/\\\/x.com\\\/Somos__Hermanos\",\"https:\\\/\\\/www.instagram.com\\\/somos__hermanos\\\/#\",\"https:\\\/\\\/www.tiktok.com\\\/@somoshermanosiap\",\"https:\\\/\\\/www.youtube.com\\\/@somoshermanosiap1201\\\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/somos-hermanos.mx\\\/#\\\/schema\\\/person\\\/8acd26a8688e659352b79b33c534872c\",\"name\":\"Jes\u00fas Pe\u00f1a Aguirre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a3d489e680e76cdf1b7ccc620e427d14f54a929f15306ea1d436efc89ee85c7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a3d489e680e76cdf1b7ccc620e427d14f54a929f15306ea1d436efc89ee85c7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a3d489e680e76cdf1b7ccc620e427d14f54a929f15306ea1d436efc89ee85c7c?s=96&d=mm&r=g\",\"caption\":\"Jes\u00fas Pe\u00f1a Aguirre\"},\"url\":\"https:\\\/\\\/somos-hermanos.mx\\\/index.php\\\/author\\\/jesus-pena-aguirre\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Infancia y derecho a la atenci\u00f3n m\u00e9dica - Historias que inspiran...","description":"Infancia y derecho a la atenci\u00f3n m\u00e9dica: descubre c\u00f3mo millones de ni\u00f1as y ni\u00f1os en M\u00e9xico enfrentan barreras para acceder","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/infancia-y-derecho-a-la-atencion-medica\/","og_locale":"es_MX","og_type":"article","og_title":"Infancia y derecho a la atenci\u00f3n m\u00e9dica - Historias que inspiran...","og_description":"Infancia y derecho a la atenci\u00f3n m\u00e9dica: descubre c\u00f3mo millones de ni\u00f1as y ni\u00f1os en M\u00e9xico enfrentan barreras para acceder","og_url":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/infancia-y-derecho-a-la-atencion-medica\/","og_site_name":"Historias que inspiran...","article_publisher":"https:\/\/www.facebook.com\/SomosHermanosIAP\/","article_published_time":"2026-05-12T23:46:31+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/somos-hermanos.mx\/wp-content\/uploads\/2026\/05\/atencion-medica.jpg","type":"image\/jpeg"}],"author":"Jes\u00fas Pe\u00f1a Aguirre","twitter_card":"summary_large_image","twitter_creator":"@Somos__Hermanos","twitter_site":"@Somos__Hermanos","twitter_misc":{"Escrito por":"Jes\u00fas Pe\u00f1a Aguirre","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/infancia-y-derecho-a-la-atencion-medica\/#article","isPartOf":{"@id":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/infancia-y-derecho-a-la-atencion-medica\/"},"author":{"name":"Jes\u00fas Pe\u00f1a Aguirre","@id":"https:\/\/somos-hermanos.mx\/#\/schema\/person\/8acd26a8688e659352b79b33c534872c"},"headline":"Infancia y derecho a la atenci\u00f3n m\u00e9dica","datePublished":"2026-05-12T23:46:31+00:00","mainEntityOfPage":{"@id":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/infancia-y-derecho-a-la-atencion-medica\/"},"wordCount":505,"commentCount":0,"publisher":{"@id":"https:\/\/somos-hermanos.mx\/#organization"},"image":{"@id":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/infancia-y-derecho-a-la-atencion-medica\/#primaryimage"},"thumbnailUrl":"https:\/\/somos-hermanos.mx\/wp-content\/uploads\/2026\/05\/atencion-medica.jpg","keywords":["atenci\u00f3n m\u00e9dica","comunidad","Derecho","infancia","infancia y derecho","salud"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/infancia-y-derecho-a-la-atencion-medica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/infancia-y-derecho-a-la-atencion-medica\/","url":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/infancia-y-derecho-a-la-atencion-medica\/","name":"Infancia y derecho a la atenci\u00f3n m\u00e9dica - Historias que inspiran...","isPartOf":{"@id":"https:\/\/somos-hermanos.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/infancia-y-derecho-a-la-atencion-medica\/#primaryimage"},"image":{"@id":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/infancia-y-derecho-a-la-atencion-medica\/#primaryimage"},"thumbnailUrl":"https:\/\/somos-hermanos.mx\/wp-content\/uploads\/2026\/05\/atencion-medica.jpg","datePublished":"2026-05-12T23:46:31+00:00","description":"Infancia y derecho a la atenci\u00f3n m\u00e9dica: descubre c\u00f3mo millones de ni\u00f1as y ni\u00f1os en M\u00e9xico enfrentan barreras para acceder","breadcrumb":{"@id":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/infancia-y-derecho-a-la-atencion-medica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/infancia-y-derecho-a-la-atencion-medica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/infancia-y-derecho-a-la-atencion-medica\/#primaryimage","url":"https:\/\/somos-hermanos.mx\/wp-content\/uploads\/2026\/05\/atencion-medica.jpg","contentUrl":"https:\/\/somos-hermanos.mx\/wp-content\/uploads\/2026\/05\/atencion-medica.jpg","width":1200,"height":630,"caption":"atenci\u00f3n m\u00e9dica"},{"@type":"BreadcrumbList","@id":"https:\/\/somos-hermanos.mx\/index.php\/2026\/05\/12\/infancia-y-derecho-a-la-atencion-medica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/somos-hermanos.mx\/"},{"@type":"ListItem","position":2,"name":"Infancia y derecho a la atenci\u00f3n m\u00e9dica"}]},{"@type":"WebSite","@id":"https:\/\/somos-hermanos.mx\/#website","url":"https:\/\/somos-hermanos.mx\/","name":"Historias que inspiran...","description":"Somos la voz del altruismo en M\u00e9xico","publisher":{"@id":"https:\/\/somos-hermanos.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/somos-hermanos.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/somos-hermanos.mx\/#organization","name":"Somos Hermanos","url":"https:\/\/somos-hermanos.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/somos-hermanos.mx\/#\/schema\/logo\/image\/","url":"https:\/\/somos-hermanos.mx\/wp-content\/uploads\/2025\/08\/SH30-1.jpeg","contentUrl":"https:\/\/somos-hermanos.mx\/wp-content\/uploads\/2025\/08\/SH30-1.jpeg","width":1600,"height":1142,"caption":"Somos Hermanos"},"image":{"@id":"https:\/\/somos-hermanos.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SomosHermanosIAP\/","https:\/\/x.com\/Somos__Hermanos","https:\/\/www.instagram.com\/somos__hermanos\/#","https:\/\/www.tiktok.com\/@somoshermanosiap","https:\/\/www.youtube.com\/@somoshermanosiap1201\/videos"]},{"@type":"Person","@id":"https:\/\/somos-hermanos.mx\/#\/schema\/person\/8acd26a8688e659352b79b33c534872c","name":"Jes\u00fas Pe\u00f1a Aguirre","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a3d489e680e76cdf1b7ccc620e427d14f54a929f15306ea1d436efc89ee85c7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a3d489e680e76cdf1b7ccc620e427d14f54a929f15306ea1d436efc89ee85c7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a3d489e680e76cdf1b7ccc620e427d14f54a929f15306ea1d436efc89ee85c7c?s=96&d=mm&r=g","caption":"Jes\u00fas Pe\u00f1a Aguirre"},"url":"https:\/\/somos-hermanos.mx\/index.php\/author\/jesus-pena-aguirre\/"}]}},"_links":{"self":[{"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/posts\/3628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3628"}],"version-history":[{"count":1,"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/posts\/3628\/revisions"}],"predecessor-version":[{"id":3630,"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/posts\/3628\/revisions\/3630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/media\/3629"}],"wp:attachment":[{"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/somos-hermanos.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}